{"id":6854,"date":"2021-07-09T02:18:45","date_gmt":"2021-07-09T02:18:45","guid":{"rendered":"https:\/\/www.yimeiglasses.com\/?post_type=product&#038;p=6854"},"modified":"2026-08-14T09:47:49","modified_gmt":"2026-08-14T09:47:49","slug":"cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173","status":"publish","type":"product","link":"https:\/\/www.yimeiglasses.com\/ar\/%d8%a7%d9%84%d9%85%d9%86%d8%aa%d8%ac\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/","title":{"rendered":"\u0646\u0638\u0627\u0631\u0627\u062a \u0634\u0645\u0633\u064a\u0629 \u0645\u0646 \u0643\u0627\u0631\u062a\u064a\u064a\u0647 \u0643\u0644\u0627\u0633\u064a\u0643 C \u062f\u064a\u0643\u0648\u0631 \u0643\u0644\u0627\u0633\u064a\u0643 C \u0645\u0639\u062f\u0646\u064a\u0629 \u0628\u062f\u0648\u0646 \u0625\u0637\u0627\u0631 CT3899173"},"content":{"rendered":"<h2>\u0646\u0638\u0627\u0631\u0627\u062a \u0634\u0645\u0633\u064a\u0629 \u0645\u0646 \u0643\u0627\u0631\u062a\u064a\u064a\u0647 \u0643\u0644\u0627\u0633\u064a\u0643 C \u062f\u064a\u0643\u0648\u0631 \u0643\u0644\u0627\u0633\u064a\u0643 C \u0645\u0639\u062f\u0646\u064a\u0629 \u0628\u062f\u0648\u0646 \u0625\u0637\u0627\u0631 CT3899173<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5658\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-1.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-1.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-1-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-1-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-1-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5659\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-2.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-2.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-2-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-2-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-2-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5660\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-3.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-3.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-3-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-3-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-3-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5661\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-4.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-4.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-4-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-4-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-4-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5662\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-5.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-5.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-5-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-5-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-5-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5663\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-6.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-6.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-6-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-6-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-6-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5664\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-7.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-7.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-7-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-7-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-7-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5665\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-8.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-8.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-8-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-8-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-8-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5666\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-9.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-9.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-9-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-9-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-9-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5668\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-10.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-10.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-10-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-10-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-10-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5670\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-15.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-15.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-15-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-15-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-15-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5672\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-16.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-16.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-16-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-16-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-16-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5673\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-17.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-17.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-17-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-17-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-17-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5675\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-22.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-22.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-22-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-22-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-22-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5677\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5679\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-24.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-24.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-24-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-24-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-24-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p style=\"text-align: left;\">","protected":false},"excerpt":{"rendered":"<p>\u0646\u0638\u0627\u0631\u0627\u062a \u0634\u0645\u0633\u064a\u0629 \u0645\u0646 \u0643\u0627\u0631\u062a\u064a\u064a\u0647 \u0643\u0644\u0627\u0633\u064a\u0643 C \u062f\u064a\u0643\u0648\u0631 \u0643\u0644\u0627\u0633\u064a\u0643 C \u0645\u0639\u062f\u0646\u064a\u0629 \u0628\u062f\u0648\u0646 \u0625\u0637\u0627\u0631 CT3899173<\/p>","protected":false},"featured_media":5677,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[16],"product_tag":[466,266,221,233],"class_list":["post-6854","product","type-product","status-publish","has-post-thumbnail","product_cat-sunglasses","product_tag-cartier","product_tag-men-sunglasses","product_tag-metal","product_tag-rimless","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses<\/title>\n<meta name=\"description\" content=\"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yimeiglasses.com\/ar\/\u0627\u0644\u0645\u0646\u062a\u062c\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses\" \/>\n<meta property=\"og:description\" content=\"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yimeiglasses.com\/ar\/\u0627\u0644\u0645\u0646\u062a\u062c\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/\" \/>\n<meta property=\"og:site_name\" content=\"Yimeiglasses\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yimeiglasses\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-14T09:47:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"643\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RaphaelDun\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/\",\"name\":\"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg\",\"datePublished\":\"2021-07-09T02:18:45+00:00\",\"dateModified\":\"2026-08-14T09:47:49+00:00\",\"description\":\"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg\",\"width\":750,\"height\":643,\"caption\":\"ct3899173-cartier-classic-c-decor-metal-rimless-sunglasses-23\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.yimeiglasses.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#website\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\",\"name\":\"YimeiGlasses\",\"description\":\"Glasses factory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yimeiglasses.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#organization\",\"name\":\"yimeiglasses\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u7eaf\u6587\u5b57logo.png\",\"contentUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u7eaf\u6587\u5b57logo.png\",\"width\":143,\"height\":143,\"caption\":\"yimeiglasses\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yimeiglasses\",\"https:\\\/\\\/x.com\\\/RaphaelDun\",\"https:\\\/\\\/www.pinterest.com\\\/Yimeiglasses\\\/\",\"https:\\\/\\\/www.instagram.com\\\/yimeiglasses\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@yimeiglasses\",\"https:\\\/\\\/www.youtube.com\\\/@yimeiglasses\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses","description":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yimeiglasses.com\/ar\/\u0627\u0644\u0645\u0646\u062a\u062c\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/","og_locale":"ar_AR","og_type":"article","og_title":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses","og_description":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses","og_url":"https:\/\/www.yimeiglasses.com\/ar\/\u0627\u0644\u0645\u0646\u062a\u062c\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/","og_site_name":"Yimeiglasses","article_publisher":"https:\/\/www.facebook.com\/yimeiglasses","article_modified_time":"2026-08-14T09:47:49+00:00","og_image":[{"width":750,"height":643,"url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@RaphaelDun","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"4 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/","url":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/","name":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses","isPartOf":{"@id":"https:\/\/www.yimeiglasses.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/#primaryimage"},"image":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg","datePublished":"2021-07-09T02:18:45+00:00","dateModified":"2026-08-14T09:47:49+00:00","description":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 Cartier Sunglasses Classic C Decor Metal Rimless CT3899173 &#8211; Yimeiglasses","breadcrumb":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/#primaryimage","url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg","contentUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/03\/CT3899173-Cartier-Classic-C-Decor-Metal-Rimless-Sunglasses-23.jpg","width":750,"height":643,"caption":"ct3899173-cartier-classic-c-decor-metal-rimless-sunglasses-23"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-classic-c-decor-metal-rimless-ct3899173\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.yimeiglasses.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.yimeiglasses.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cartier Sunglasses Classic C Decor Metal Rimless CT3899173"}]},{"@type":"WebSite","@id":"https:\/\/www.yimeiglasses.com\/#website","url":"https:\/\/www.yimeiglasses.com\/","name":"YimeiGlasses","description":"Glasses factory","publisher":{"@id":"https:\/\/www.yimeiglasses.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yimeiglasses.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.yimeiglasses.com\/#organization","name":"yimeiglasses","url":"https:\/\/www.yimeiglasses.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.yimeiglasses.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2022\/12\/\u7eaf\u6587\u5b57logo.png","contentUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2022\/12\/\u7eaf\u6587\u5b57logo.png","width":143,"height":143,"caption":"yimeiglasses"},"image":{"@id":"https:\/\/www.yimeiglasses.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yimeiglasses","https:\/\/x.com\/RaphaelDun","https:\/\/www.pinterest.com\/Yimeiglasses\/","https:\/\/www.instagram.com\/yimeiglasses\/","https:\/\/www.tiktok.com\/@yimeiglasses","https:\/\/www.youtube.com\/@yimeiglasses"]}]}},"_links":{"self":[{"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/product\/6854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/media\/5677"}],"wp:attachment":[{"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/media?parent=6854"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/product_brand?post=6854"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/product_cat?post=6854"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ar\/wp-json\/wp\/v2\/product_tag?post=6854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}