{"id":11753,"date":"2023-03-17T02:32:51","date_gmt":"2023-03-17T02:32:51","guid":{"rendered":"https:\/\/www.yimeiglasses.com\/?post_type=product&#038;p=11753"},"modified":"2026-08-14T09:52:06","modified_gmt":"2026-08-14T09:52:06","slug":"cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s","status":"publish","type":"product","link":"https:\/\/www.yimeiglasses.com\/fr\/produit\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/","title":{"rendered":"Cartier Eyeglasses Lunettes de soleil Lentille circulaire M\u00e9tal R\u00e9tro Pleine Monture CT0110s"},"content":{"rendered":"<h2>Cartier Eyeglasses Lunettes de soleil Lentille circulaire M\u00e9tal R\u00e9tro Pleine Monture CT0110s<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6344\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Optical-Glasses-CT0110s-1.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6345\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Optical-Glasses-CT0110s-2.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6346\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Optical-Glasses-CT0110s-3.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6347\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Optical-Glasses-CT0110s-4.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6348\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Optical-Glasses-CT0110s-5.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6349\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Optical-Glasses-CT0110s-6.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6350\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-1.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6351\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-2.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6352\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-3.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6353\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6354\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-5.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6355\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-6.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6356\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-7.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6357\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-8.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6358\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-9.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6359\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-10.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6360\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-11.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6361\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-12.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6362\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-13.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6363\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-14.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6364\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-15.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6365\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-16.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6366\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-17.jpg\" alt=\"\" width=\"750\" height=\"650\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6367\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-18.jpg\" alt=\"\" width=\"750\" height=\"650\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Cartier Eyeglasses Lunettes de soleil Lentille circulaire M\u00e9tal R\u00e9tro Pleine Monture CT0110s<\/p>","protected":false},"featured_media":11183,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[17,16],"product_tag":[225,219,221,231,218],"class_list":["post-11753","product","type-product","status-publish","has-post-thumbnail","product_cat-eyeglasses","product_cat-sunglasses","product_tag-aviators","product_tag-full-frame","product_tag-metal","product_tag-pilot","product_tag-sunglasses","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses<\/title>\n<meta name=\"description\" content=\"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yimeiglasses.com\/fr\/produit\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses\" \/>\n<meta property=\"og:description\" content=\"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yimeiglasses.com\/fr\/produit\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/\" \/>\n<meta property=\"og:site_name\" content=\"Yimeiglasses\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yimeiglasses\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-14T09:52:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RaphaelDun\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/\",\"name\":\"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg\",\"datePublished\":\"2023-03-17T02:32:51+00:00\",\"dateModified\":\"2026-08-14T09:52:06+00:00\",\"description\":\"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg\",\"width\":750,\"height\":650,\"caption\":\"cartier-circular-lens-metal-retro-full-frame-sunglasses-ct0110s-4\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.yimeiglasses.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#website\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\",\"name\":\"YimeiGlasses\",\"description\":\"Glasses factory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yimeiglasses.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#organization\",\"name\":\"yimeiglasses\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u7eaf\u6587\u5b57logo.png\",\"contentUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u7eaf\u6587\u5b57logo.png\",\"width\":143,\"height\":143,\"caption\":\"yimeiglasses\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yimeiglasses\",\"https:\\\/\\\/x.com\\\/RaphaelDun\",\"https:\\\/\\\/www.pinterest.com\\\/Yimeiglasses\\\/\",\"https:\\\/\\\/www.instagram.com\\\/yimeiglasses\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@yimeiglasses\",\"https:\\\/\\\/www.youtube.com\\\/@yimeiglasses\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses","description":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yimeiglasses.com\/fr\/produit\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/","og_locale":"fr_FR","og_type":"article","og_title":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses","og_description":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses","og_url":"https:\/\/www.yimeiglasses.com\/fr\/produit\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/","og_site_name":"Yimeiglasses","article_publisher":"https:\/\/www.facebook.com\/yimeiglasses","article_modified_time":"2026-08-14T09:52:06+00:00","og_image":[{"width":750,"height":650,"url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@RaphaelDun","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/","url":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/","name":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses","isPartOf":{"@id":"https:\/\/www.yimeiglasses.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/#primaryimage"},"image":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg","datePublished":"2023-03-17T02:32:51+00:00","dateModified":"2026-08-14T09:52:06+00:00","description":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s &#8211; Yimeiglasses","breadcrumb":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/#primaryimage","url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg","contentUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2023\/03\/Cartier-Circular-lens-Metal-Retro-Full-Frame-Sunglasses-CT0110s-4.jpg","width":750,"height":650,"caption":"cartier-circular-lens-metal-retro-full-frame-sunglasses-ct0110s-4"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-eyeglasses-sunglasses-circular-lens-metal-retro-full-frame-ct0110s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.yimeiglasses.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.yimeiglasses.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cartier Eyeglasses Sunglasses Circular lens Metal Retro Full Frame CT0110s"}]},{"@type":"WebSite","@id":"https:\/\/www.yimeiglasses.com\/#website","url":"https:\/\/www.yimeiglasses.com\/","name":"YimeiGlasses","description":"Glasses factory","publisher":{"@id":"https:\/\/www.yimeiglasses.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yimeiglasses.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.yimeiglasses.com\/#organization","name":"yimeiglasses","url":"https:\/\/www.yimeiglasses.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yimeiglasses.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2022\/12\/\u7eaf\u6587\u5b57logo.png","contentUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2022\/12\/\u7eaf\u6587\u5b57logo.png","width":143,"height":143,"caption":"yimeiglasses"},"image":{"@id":"https:\/\/www.yimeiglasses.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yimeiglasses","https:\/\/x.com\/RaphaelDun","https:\/\/www.pinterest.com\/Yimeiglasses\/","https:\/\/www.instagram.com\/yimeiglasses\/","https:\/\/www.tiktok.com\/@yimeiglasses","https:\/\/www.youtube.com\/@yimeiglasses"]}]}},"_links":{"self":[{"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/product\/11753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/media\/11183"}],"wp:attachment":[{"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/media?parent=11753"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/product_brand?post=11753"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/product_cat?post=11753"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/fr\/wp-json\/wp\/v2\/product_tag?post=11753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}