{"id":6807,"date":"2021-07-02T04:04:21","date_gmt":"2021-07-02T04:04:21","guid":{"rendered":"https:\/\/www.yimeiglasses.com\/?post_type=product&#038;p=6807"},"modified":"2026-08-14T09:47:50","modified_gmt":"2026-08-14T09:47:50","slug":"cartier-sunglasses-wooden-rimless-classic-metal-ct4189706","status":"publish","type":"product","link":"https:\/\/www.yimeiglasses.com\/ru\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/","title":{"rendered":"Cartier \u0421\u043e\u043b\u043d\u0446\u0435\u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0435 \u043e\u0447\u043a\u0438 \u0434\u0435\u0440\u0435\u0432\u044f\u043d\u043d\u044b\u0435 \u0431\u0435\u0437 \u043e\u043f\u0440\u0430\u0432\u044b \u043a\u043b\u0430\u0441\u0441\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u043c\u0435\u0442\u0430\u043b\u043b\u0438\u0447\u0435\u0441\u043a\u0438\u0435 CT4189706"},"content":{"rendered":"<h2>Cartier \u0421\u043e\u043b\u043d\u0446\u0435\u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0435 \u043e\u0447\u043a\u0438 \u0434\u0435\u0440\u0435\u0432\u044f\u043d\u043d\u044b\u0435 \u0431\u0435\u0437 \u043e\u043f\u0440\u0430\u0432\u044b \u043a\u043b\u0430\u0441\u0441\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u043c\u0435\u0442\u0430\u043b\u043b\u0438\u0447\u0435\u0441\u043a\u0438\u0435 CT4189706<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6822\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-1.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-1.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-1-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-1-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-1-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6823\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-2.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-2.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-2-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-2-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-2-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6824\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-3.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-3.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-3-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-3-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-3-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6825\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-4.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-4.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-4-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-4-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-4-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6826\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-5.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-5.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-5-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-5-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-5-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6827\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-6.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-6.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-6-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-6-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-6-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6828\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-7.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-7.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-7-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-7-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-7-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6829\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-8.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-8.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-8-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-8-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-8-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6830\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-9.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-9.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-9-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-9-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-9-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6831\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-14.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-14.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-14-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-14-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-14-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6832\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg\" alt=\"\" width=\"750\" height=\"643\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15-247x212.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15-510x437.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15-14x12.jpg 14w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6833\" src=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-16.jpg\" alt=\"\" width=\"750\" height=\"400\" srcset=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-16.jpg 750w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-16-247x132.jpg 247w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-16-510x272.jpg 510w, https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-16-18x10.jpg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Cartier \u0421\u043e\u043b\u043d\u0446\u0435\u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0435 \u043e\u0447\u043a\u0438 \u0434\u0435\u0440\u0435\u0432\u044f\u043d\u043d\u044b\u0435 \u0431\u0435\u0437 \u043e\u043f\u0440\u0430\u0432\u044b \u043a\u043b\u0430\u0441\u0441\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u043c\u0435\u0442\u0430\u043b\u043b\u0438\u0447\u0435\u0441\u043a\u0438\u0435 CT4189706<\/p>","protected":false},"featured_media":6832,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[16,18],"product_tag":[466,228,233,218,226],"class_list":["post-6807","product","type-product","status-publish","has-post-thumbnail","product_cat-sunglasses","product_cat-wooden-glasses","product_tag-cartier","product_tag-classic","product_tag-rimless","product_tag-sunglasses","product_tag-wooden","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses<\/title>\n<meta name=\"description\" content=\"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yimeiglasses.com\/ru\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses\" \/>\n<meta property=\"og:description\" content=\"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yimeiglasses.com\/ru\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/\" \/>\n<meta property=\"og:site_name\" content=\"Yimeiglasses\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yimeiglasses\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-14T09:47:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"643\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RaphaelDun\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/\",\"name\":\"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg\",\"datePublished\":\"2021-07-02T04:04:21+00:00\",\"dateModified\":\"2026-08-14T09:47:50+00:00\",\"description\":\"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg\",\"width\":750,\"height\":643,\"caption\":\"ct4189706-cartier-wooden-rimless-classic-metal-sunglasses-15\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/product\\\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.yimeiglasses.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#website\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\",\"name\":\"YimeiGlasses\",\"description\":\"Glasses factory\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yimeiglasses.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#organization\",\"name\":\"yimeiglasses\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u7eaf\u6587\u5b57logo.png\",\"contentUrl\":\"https:\\\/\\\/www.yimeiglasses.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u7eaf\u6587\u5b57logo.png\",\"width\":143,\"height\":143,\"caption\":\"yimeiglasses\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yimeiglasses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yimeiglasses\",\"https:\\\/\\\/x.com\\\/RaphaelDun\",\"https:\\\/\\\/www.pinterest.com\\\/Yimeiglasses\\\/\",\"https:\\\/\\\/www.instagram.com\\\/yimeiglasses\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@yimeiglasses\",\"https:\\\/\\\/www.youtube.com\\\/@yimeiglasses\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses","description":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yimeiglasses.com\/ru\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/","og_locale":"ru_RU","og_type":"article","og_title":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses","og_description":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses","og_url":"https:\/\/www.yimeiglasses.com\/ru\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/","og_site_name":"Yimeiglasses","article_publisher":"https:\/\/www.facebook.com\/yimeiglasses","article_modified_time":"2026-08-14T09:47:50+00:00","og_image":[{"width":750,"height":643,"url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@RaphaelDun","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"3 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/","url":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/","name":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses","isPartOf":{"@id":"https:\/\/www.yimeiglasses.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/#primaryimage"},"image":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg","datePublished":"2021-07-02T04:04:21+00:00","dateModified":"2026-08-14T09:47:50+00:00","description":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 Cartier Sunglasses Wooden Rimless Classic Metal CT4189706 &#8211; Yimeiglasses","breadcrumb":{"@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/#primaryimage","url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg","contentUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2021\/07\/CT4189706-Cartier-Wooden-Rimless-Classic-Metal-Sunglasses-15.jpg","width":750,"height":643,"caption":"ct4189706-cartier-wooden-rimless-classic-metal-sunglasses-15"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yimeiglasses.com\/product\/cartier-sunglasses-wooden-rimless-classic-metal-ct4189706\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.yimeiglasses.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.yimeiglasses.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cartier Sunglasses Wooden Rimless Classic Metal CT4189706"}]},{"@type":"WebSite","@id":"https:\/\/www.yimeiglasses.com\/#website","url":"https:\/\/www.yimeiglasses.com\/","name":"YimeiGlasses","description":"Glasses factory","publisher":{"@id":"https:\/\/www.yimeiglasses.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yimeiglasses.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/www.yimeiglasses.com\/#organization","name":"yimeiglasses","url":"https:\/\/www.yimeiglasses.com\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.yimeiglasses.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2022\/12\/\u7eaf\u6587\u5b57logo.png","contentUrl":"https:\/\/www.yimeiglasses.com\/wp-content\/uploads\/2022\/12\/\u7eaf\u6587\u5b57logo.png","width":143,"height":143,"caption":"yimeiglasses"},"image":{"@id":"https:\/\/www.yimeiglasses.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yimeiglasses","https:\/\/x.com\/RaphaelDun","https:\/\/www.pinterest.com\/Yimeiglasses\/","https:\/\/www.instagram.com\/yimeiglasses\/","https:\/\/www.tiktok.com\/@yimeiglasses","https:\/\/www.youtube.com\/@yimeiglasses"]}]}},"_links":{"self":[{"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/product\/6807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/media\/6832"}],"wp:attachment":[{"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/media?parent=6807"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/product_brand?post=6807"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/product_cat?post=6807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.yimeiglasses.com\/ru\/wp-json\/wp\/v2\/product_tag?post=6807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}